{"id":35812,"date":"2013-11-05T23:33:08","date_gmt":"2013-11-05T23:33:08","guid":{"rendered":"https:\/\/wpml.lisbonsightsailing.com\/contatos\/"},"modified":"2026-07-27T15:48:40","modified_gmt":"2026-07-27T15:48:40","slug":"contacts","status":"publish","type":"page","link":"https:\/\/wpml.lisbonsightsailing.com\/en\/contacts\/","title":{"rendered":"Contact"},"content":{"rendered":"<h2>Precisa de ajuda?<\/h2>\n<p>Precisa de algo? Tem alguma d\u00favida? Gostava de saber mais sobre &#8230; N\u00e3o hesite e &#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Precisa de ajuda? Precisa de algo? Tem alguma d\u00favida? Gostava de saber mais sobre &#8230; N\u00e3o hesite e &#8230;<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"menu_order":140,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"estilo-lss":[],"evolucao-tarefa":[],"relevancia-tarefa":[],"hf_cat_page":[1654],"class_list":["post-35812","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/pages\/35812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/comments?post=35812"}],"version-history":[{"count":2,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/pages\/35812\/revisions"}],"predecessor-version":[{"id":72984,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/pages\/35812\/revisions\/72984"}],"wp:attachment":[{"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/media?parent=35812"}],"wp:term":[{"taxonomy":"estilo-lss","embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/estilo-lss?post=35812"},{"taxonomy":"evolucao-tarefa","embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/evolucao-tarefa?post=35812"},{"taxonomy":"relevancia-tarefa","embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/relevancia-tarefa?post=35812"},{"taxonomy":"hf_cat_page","embeddable":true,"href":"https:\/\/wpml.lisbonsightsailing.com\/en\/wp-json\/wp\/v2\/hf_cat_page?post=35812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}